{"id":2284,"date":"2021-02-23T06:25:59","date_gmt":"2021-02-23T06:25:59","guid":{"rendered":"https:\/\/hannebang.w6.pixact.dk\/datenschutzerklaerung\/"},"modified":"2026-06-12T10:14:23","modified_gmt":"2026-06-12T10:14:23","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/hannebang.w6.pixact.dk\/de\/datenschutzerklaerung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Wer wir sind<\/h2>\n\n<p class=\"wp-block-paragraph\">Unsere Website-Adresse lautet: http:\/\/klbtheme.com\/cosmetsy.<\/p>\n\n<h2 class=\"wp-block-heading\">Welche personenbezogenen Daten wir sammeln und warum wir sie sammeln<\/h2>\n\n<h3 class=\"wp-block-heading\">Kommentare<\/h3>\n\n<p class=\"wp-block-paragraph\">Wenn Besucher Kommentare auf der Website hinterlassen, erfassen wir die im Kommentarformular angezeigten Daten sowie die IP-Adresse des Besuchers und den Browser-User-Agent-String, um die Spam-Erkennung zu unterst\u00fctzen.<\/p>\n\n<p class=\"wp-block-paragraph\">Eine anonymisierte Zeichenfolge, die aus Ihrer E-Mail-Adresse erstellt wird (auch Hash genannt), kann dem Gravatar-Dienst bereitgestellt werden, um zu pr\u00fcfen, ob Sie diesen nutzen. Die Datenschutzerkl\u00e4rung des Gravatar-Dienstes finden Sie hier: https:\/\/automattic.com\/privacy\/. Nach Freigabe Ihres Kommentars ist Ihr Profilbild im Zusammenhang mit Ihrem Kommentar \u00f6ffentlich sichtbar.<\/p>\n\n<h3 class=\"wp-block-heading\">Medien<\/h3>\n\n<p class=\"wp-block-paragraph\">Wenn Sie Bilder auf die Website hochladen, sollten Sie vermeiden, Bilder mit eingebetteten Standortdaten (EXIF GPS) hochzuladen. Besucher der Website k\u00f6nnen Standortdaten aus Bildern auf der Website herunterladen und extrahieren.<\/p>\n\n<h3 class=\"wp-block-heading\">Kontaktformulare<\/h3>\n\n<h3 class=\"wp-block-heading\">Cookies<\/h3>\n\n<p class=\"wp-block-paragraph\">Wenn Sie einen Kommentar auf unserer Website hinterlassen, k\u00f6nnen Sie zustimmen, dass Ihr Name, Ihre E-Mail-Adresse und Ihre Website in Cookies gespeichert werden. Dies dient Ihrem Komfort, damit Sie Ihre Daten nicht erneut eingeben m\u00fcssen, wenn Sie einen weiteren Kommentar hinterlassen. Diese Cookies bleiben ein Jahr lang gespeichert.<\/p>\n\n<p class=\"wp-block-paragraph\">Wenn Sie unsere Anmeldeseite besuchen, setzen wir ein tempor\u00e4res Cookie, um festzustellen, ob Ihr Browser Cookies akzeptiert. Dieses Cookie enth\u00e4lt keine personenbezogenen Daten und wird gel\u00f6scht, wenn Sie Ihren Browser schlie\u00dfen.<\/p>\n\n<p class=\"wp-block-paragraph\">Wenn Sie sich anmelden, setzen wir au\u00dferdem mehrere Cookies, um Ihre Anmeldeinformationen und Anzeigeoptionen zu speichern. Anmelde-Cookies bleiben zwei Tage lang gespeichert, Anzeigeoptionen ein Jahr. Wenn Sie \u201eAngemeldet bleiben\u201c ausw\u00e4hlen, bleibt Ihre Anmeldung zwei Wochen lang bestehen. Wenn Sie sich von Ihrem Konto abmelden, werden die Anmelde-Cookies entfernt.<\/p>\n\n<p class=\"wp-block-paragraph\">Wenn Sie einen Artikel bearbeiten oder ver\u00f6ffentlichen, wird ein zus\u00e4tzliches Cookie in Ihrem Browser gespeichert. Dieses Cookie enth\u00e4lt keine personenbezogenen Daten und zeigt lediglich die Beitrags-ID des gerade bearbeiteten Artikels an. Es l\u00e4uft nach einem Tag ab.<\/p>\n\n<h3 class=\"wp-block-heading\">Eingebettete Inhalte von anderen Websites<\/h3>\n\n<p class=\"wp-block-paragraph\">Beitr\u00e4ge auf dieser Website k\u00f6nnen eingebettete Inhalte enthalten (z. B. Videos, Bilder, Artikel usw.). Eingebettete Inhalte von anderen Websites verhalten sich genau so, als h\u00e4tte der Besucher die andere Website besucht.<\/p>\n\n<p class=\"wp-block-paragraph\">Diese Websites k\u00f6nnen Daten \u00fcber Sie sammeln, Cookies verwenden, zus\u00e4tzliche Tracking-Dienste Dritter einbetten und Ihre Interaktion mit diesen eingebetteten Inhalten \u00fcberwachen, einschlie\u00dflich der Verfolgung Ihrer Interaktion, wenn Sie ein Konto haben und auf dieser Website angemeldet sind.<\/p>\n\n<h3 class=\"wp-block-heading\">Analysen<\/h3>\n\n<h2 class=\"wp-block-heading\">Mit wem wir Ihre Daten teilen<\/h2>\n\n<p class=\"wp-block-paragraph\">Wenn Sie eine Passwortzur\u00fccksetzung anfordern, wird Ihre IP-Adresse in der E-Mail zur Zur\u00fccksetzung enthalten sein.<\/p>\n\n<h2 class=\"wp-block-heading\">Wie lange wir Ihre Daten speichern<\/h2>\n\n<p class=\"wp-block-paragraph\">Wenn Sie einen Kommentar hinterlassen, werden der Kommentar und seine Metadaten unbegrenzt gespeichert. So k\u00f6nnen wir Folgekommentare automatisch erkennen und freigeben, anstatt sie in einer Moderationswarteschlange zu halten.<\/p>\n\n<p class=\"wp-block-paragraph\">F\u00fcr Nutzer, die sich auf unserer Website registrieren (falls vorhanden), speichern wir au\u00dferdem die personenbezogenen Informationen, die sie in ihrem Benutzerprofil angeben. Alle Nutzer k\u00f6nnen ihre personenbezogenen Informationen jederzeit einsehen, bearbeiten oder l\u00f6schen (mit Ausnahme ihres Benutzernamens). Website-Administratoren k\u00f6nnen diese Informationen ebenfalls einsehen und bearbeiten.<\/p>\n\n<h2 class=\"wp-block-heading\">Welche Rechte Sie an Ihren Daten haben<\/h2>\n\n<p class=\"wp-block-paragraph\">Wenn Sie ein Konto auf dieser Website haben oder Kommentare hinterlassen haben, k\u00f6nnen Sie den Export einer Datei mit den personenbezogenen Daten anfordern, die wir \u00fcber Sie gespeichert haben, einschlie\u00dflich aller Daten, die Sie uns bereitgestellt haben. Sie k\u00f6nnen au\u00dferdem verlangen, dass wir alle personenbezogenen Daten l\u00f6schen, die wir \u00fcber Sie gespeichert haben. Dies umfasst keine Daten, die wir aus administrativen, rechtlichen oder Sicherheitsgr\u00fcnden aufbewahren m\u00fcssen.<\/p>\n\n<h2 class=\"wp-block-heading\">Wohin wir Ihre Daten senden<\/h2>\n\n<p class=\"wp-block-paragraph\">Besucherkommentare k\u00f6nnen durch einen automatisierten Dienst zur Spam-Erkennung gepr\u00fcft werden.<\/p>\n\n<h2 class=\"wp-block-heading\">Ihre Kontaktinformationen<\/h2>\n\n<h2 class=\"wp-block-heading\">Zus\u00e4tzliche Informationen<\/h2>\n\n<h3 class=\"wp-block-heading\">Wie wir Ihre Daten sch\u00fctzen<\/h3>\n\n<h3 class=\"wp-block-heading\">Welche Verfahren wir bei Datenschutzverletzungen eingerichtet haben<\/h3>\n\n<h3 class=\"wp-block-heading\">Von welchen Dritten wir Daten erhalten<\/h3>\n\n<h3 class=\"wp-block-heading\">Welche automatisierte Entscheidungsfindung und\/oder Profilerstellung wir mit Nutzerdaten durchf\u00fchren<\/h3>\n\n<h3 class=\"wp-block-heading\">Branchenspezifische Offenlegungspflichten<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Wer wir sind Unsere Website-Adresse lautet: http:\/\/klbtheme.com\/cosmetsy. Welche personenbezogenen Daten wir sammeln und warum wir sie sammeln Kommentare Wenn Besucher Kommentare auf der Website hinterlassen, erfassen wir die im Kommentarformular angezeigten Daten sowie die IP-Adresse des Besuchers und den Browser-User-Agent-String, um die Spam-Erkennung zu unterst\u00fctzen. Eine anonymisierte Zeichenfolge, die aus Ihrer E-Mail-Adresse erstellt wird (auch<\/p>\n<div class=\"klb-readmore entry-button\"><a class=\"button light alt medium\" href=\"https:\/\/hannebang.w6.pixact.dk\/de\/datenschutzerklaerung\/\">Read More<\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-2284","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datenschutzerkl\u00e4rung - Hanne Bang<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hannebang.w6.pixact.dk\/de\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutzerkl\u00e4rung - Hanne Bang\" \/>\n<meta property=\"og:description\" content=\"Wer wir sind Unsere Website-Adresse lautet: http:\/\/klbtheme.com\/cosmetsy. Welche personenbezogenen Daten wir sammeln und warum wir sie sammeln Kommentare Wenn Besucher Kommentare auf der Website hinterlassen, erfassen wir die im Kommentarformular angezeigten Daten sowie die IP-Adresse des Besuchers und den Browser-User-Agent-String, um die Spam-Erkennung zu unterst\u00fctzen. Eine anonymisierte Zeichenfolge, die aus Ihrer E-Mail-Adresse erstellt wird (auchRead More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hannebang.w6.pixact.dk\/de\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:site_name\" content=\"Hanne Bang\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-12T10:14:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hannebang.w6.pixact.dk\\\/de\\\/datenschutzerklaerung\\\/\",\"url\":\"https:\\\/\\\/hannebang.w6.pixact.dk\\\/de\\\/datenschutzerklaerung\\\/\",\"name\":\"Datenschutzerkl\u00e4rung - Hanne Bang\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hannebang.w6.pixact.dk\\\/de\\\/#website\"},\"datePublished\":\"2021-02-23T06:25:59+00:00\",\"dateModified\":\"2026-06-12T10:14:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hannebang.w6.pixact.dk\\\/de\\\/datenschutzerklaerung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hannebang.w6.pixact.dk\\\/de\\\/datenschutzerklaerung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hannebang.w6.pixact.dk\\\/de\\\/datenschutzerklaerung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hannebang.w6.pixact.dk\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutzerkl\u00e4rung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hannebang.w6.pixact.dk\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/hannebang.w6.pixact.dk\\\/de\\\/\",\"name\":\"Hanne Bang\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hannebang.w6.pixact.dk\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutzerkl\u00e4rung - Hanne Bang","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hannebang.w6.pixact.dk\/de\/datenschutzerklaerung\/","og_locale":"de_DE","og_type":"article","og_title":"Datenschutzerkl\u00e4rung - Hanne Bang","og_description":"Wer wir sind Unsere Website-Adresse lautet: http:\/\/klbtheme.com\/cosmetsy. Welche personenbezogenen Daten wir sammeln und warum wir sie sammeln Kommentare Wenn Besucher Kommentare auf der Website hinterlassen, erfassen wir die im Kommentarformular angezeigten Daten sowie die IP-Adresse des Besuchers und den Browser-User-Agent-String, um die Spam-Erkennung zu unterst\u00fctzen. Eine anonymisierte Zeichenfolge, die aus Ihrer E-Mail-Adresse erstellt wird (auchRead More","og_url":"https:\/\/hannebang.w6.pixact.dk\/de\/datenschutzerklaerung\/","og_site_name":"Hanne Bang","article_modified_time":"2026-06-12T10:14:23+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hannebang.w6.pixact.dk\/de\/datenschutzerklaerung\/","url":"https:\/\/hannebang.w6.pixact.dk\/de\/datenschutzerklaerung\/","name":"Datenschutzerkl\u00e4rung - Hanne Bang","isPartOf":{"@id":"https:\/\/hannebang.w6.pixact.dk\/de\/#website"},"datePublished":"2021-02-23T06:25:59+00:00","dateModified":"2026-06-12T10:14:23+00:00","breadcrumb":{"@id":"https:\/\/hannebang.w6.pixact.dk\/de\/datenschutzerklaerung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hannebang.w6.pixact.dk\/de\/datenschutzerklaerung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hannebang.w6.pixact.dk\/de\/datenschutzerklaerung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hannebang.w6.pixact.dk\/de\/"},{"@type":"ListItem","position":2,"name":"Datenschutzerkl\u00e4rung"}]},{"@type":"WebSite","@id":"https:\/\/hannebang.w6.pixact.dk\/de\/#website","url":"https:\/\/hannebang.w6.pixact.dk\/de\/","name":"Hanne Bang","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hannebang.w6.pixact.dk\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/hannebang.w6.pixact.dk\/de\/wp-json\/wp\/v2\/pages\/2284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hannebang.w6.pixact.dk\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hannebang.w6.pixact.dk\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hannebang.w6.pixact.dk\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hannebang.w6.pixact.dk\/de\/wp-json\/wp\/v2\/comments?post=2284"}],"version-history":[{"count":1,"href":"https:\/\/hannebang.w6.pixact.dk\/de\/wp-json\/wp\/v2\/pages\/2284\/revisions"}],"predecessor-version":[{"id":2285,"href":"https:\/\/hannebang.w6.pixact.dk\/de\/wp-json\/wp\/v2\/pages\/2284\/revisions\/2285"}],"wp:attachment":[{"href":"https:\/\/hannebang.w6.pixact.dk\/de\/wp-json\/wp\/v2\/media?parent=2284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}